{"id":862,"date":"2021-05-19T13:32:36","date_gmt":"2021-05-19T13:32:36","guid":{"rendered":"http:\/\/mosqueedelognes.com\/?page_id=862"},"modified":"2022-12-15T11:07:14","modified_gmt":"2022-12-15T10:07:14","slug":"charity-home-2","status":"publish","type":"page","link":"https:\/\/mosqueedelognes.com\/","title":{"rendered":"Accueil"},"content":{"rendered":"<p><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-1 fusion-flex-container nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-padding-top-small:30px;--awb-padding-bottom-small:30px;--awb-margin-top:80px;--awb-min-height:100vh;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-center fusion-flex-justify-content-center fusion-flex-content-wrap\" style=\"max-width:1216.8px;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-0 fusion_builder_column_1_1 1_1 fusion-flex-column fusion-animated\" style=\"--awb-bg-size:cover;--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:20px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\" data-animationType=\"fadeInUp\" data-animationDuration=\"0.8\" data-animationOffset=\"top-into-view\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-title title fusion-title-1 fusion-sep-none fusion-title-center fusion-title-text fusion-title-size-one\" style=\"--awb-margin-top-small:0px;--awb-margin-right-small:0px;--awb-margin-bottom-small:20px;--awb-margin-left-small:0px;\"><h1 class=\"fusion-title-heading title-heading-center\" style=\"font-family:&quot;Pacifico&quot;;font-style:normal;font-weight:400;margin:0;text-transform:capitalize;\">Faisons de ce r\u00eave une r\u00e9alit\u00e9&#8230;<\/h1><\/div><div class=\"fusion-video fusion-youtube\" style=\"--awb-max-width:600px;--awb-max-height:360px;--awb-align-self:center;--awb-width:100%;\" data-autoplay=\"1\"><div class=\"video-shortcode\"><lite-youtube videoid=\"R850_BdvBww\" class=\"landscape\" params=\"wmode=transparent&autoplay=1&amp;enablejsapi=1\" title=\"YouTube video player 1\" data-button-label=\"Play Video\" width=\"600\" height=\"360\" data-thumbnail-size=\"auto\" data-no-cookie=\"on\"><\/lite-youtube><\/div><\/div><div class=\"fusion-separator fusion-full-width-sep\" style=\"align-self: center;margin-left: auto;margin-right: auto;width:100%;\"><div class=\"fusion-separator-border sep-single\" style=\"--awb-height:20px;--awb-amount:20px;--awb-sep-color:var(--awb-color1);border-color:var(--awb-color1);border-top-width:20px;\"><\/div><\/div><div class=\"fusion-builder-row fusion-builder-row-inner fusion-row fusion-flex-align-items-center fusion-flex-justify-content-center fusion-flex-content-wrap\" style=\"--awb-flex-grow:0;--awb-flex-grow-medium:0;--awb-flex-grow-small:0;--awb-flex-shrink:0;--awb-flex-shrink-medium:0;--awb-flex-shrink-small:0;width:104% !important;max-width:104% !important;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column_inner fusion-builder-nested-column-0 fusion_builder_column_inner_1_1 1_1 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:0px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-center fusion-content-layout-row\"><div ><a class=\"fusion-button button-flat button-large button-custom fusion-button-default button-1 fusion-button-default-span fusion-button-default-type\" style=\"--awb-margin-right:10px;--button_accent_color:var(--awb-color1);--button_accent_hover_color:var(--awb-color1);--button_border_hover_color:var(--awb-color1);--button_border_width-top:2px;--button_border_width-right:2px;--button_border_width-bottom:2px;--button_border_width-left:2px;--button_gradient_top_color:var(--awb-custom_color_1);--button_gradient_bottom_color:var(--awb-custom_color_1);--button_gradient_top_color_hover:var(--awb-custom_color_1);--button_gradient_bottom_color_hover:var(--awb-custom_color_1);\" target=\"_self\" href=\"https:\/\/www.helloasso.com\/associations\/association-fraternelle-multiculturelle-de-lognes\/formulaires\/1\"><span class=\"fusion-button-text awb-button__text awb-button__text--default\">DON VIA HELLOASSO<\/span><\/a><\/div><div ><a class=\"fusion-button button-flat button-large button-custom fusion-button-default button-2 fusion-button-default-span fusion-button-default-type\" style=\"--awb-margin-left:10px;--button_accent_color:var(--awb-custom_color_1);--button_border_color:var(--awb-custom_color_1);--button_accent_hover_color:var(--awb-custom_color_1);--button_border_hover_color:var(--awb-custom_color_1);--button_border_width-top:2px;--button_border_width-right:2px;--button_border_width-bottom:2px;--button_border_width-left:2px;--button_gradient_top_color:var(--awb-color1);--button_gradient_bottom_color:var(--awb-color1);--button_gradient_top_color_hover:var(--awb-color1);--button_gradient_bottom_color_hover:var(--awb-color1);\" target=\"_self\" href=\"https:\/\/www.paypal.com\/paypalme\/DonAFMLMdL77?locale.x=fr_FR\"><span class=\"fusion-button-text awb-button__text awb-button__text--default\">DON VIA PAYPAL<\/span><\/a><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":4,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"100-width.php","meta":{"footnotes":""},"class_list":["post-862","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Mosqu\u00e9e de Lognes \u2013 AFML<\/title>\n<meta name=\"description\" content=\"\u0627\u0644\u0633\u0644\u0627\u0645 \u0639\u0644\u064a\u0643\u0645 \u0648 \u0631\u062d\u0645\u0629 \u0627\u0644\u0644\u0647 \u0648 \u0628\u0631\u0643\u0627\u062a\u0647 \u2013 Bienvenue sur le site officiel de la mosqu\u00e9e de Lognes, entrez-y en paix. Bonne visite ! ;)\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mosqueedelognes.com\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mosqu\u00e9e de Lognes \u2013 AFML\" \/>\n<meta property=\"og:description\" content=\"\u0627\u0644\u0633\u0644\u0627\u0645 \u0639\u0644\u064a\u0643\u0645 \u0648 \u0631\u062d\u0645\u0629 \u0627\u0644\u0644\u0647 \u0648 \u0628\u0631\u0643\u0627\u062a\u0647 \u2013 Bienvenue sur le site officiel de la mosqu\u00e9e de Lognes, entrez-y en paix. Bonne visite ! ;)\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mosqueedelognes.com\/\" \/>\n<meta property=\"og:site_name\" content=\"Mosqu\u00e9e de Lognes \u2013 AFML\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/mosqueedelognes\/\" \/>\n<meta property=\"article:modified_time\" content=\"2022-12-15T10:07:14+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@Mosquee_Lognes\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/mosqueedelognes.com\\\/\",\"url\":\"https:\\\/\\\/mosqueedelognes.com\\\/\",\"name\":\"Mosqu\u00e9e de Lognes \u2013 AFML\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mosqueedelognes.com\\\/#website\"},\"datePublished\":\"2021-05-19T13:32:36+00:00\",\"dateModified\":\"2022-12-15T10:07:14+00:00\",\"description\":\"\u0627\u0644\u0633\u0644\u0627\u0645 \u0639\u0644\u064a\u0643\u0645 \u0648 \u0631\u062d\u0645\u0629 \u0627\u0644\u0644\u0647 \u0648 \u0628\u0631\u0643\u0627\u062a\u0647 \u2013 Bienvenue sur le site officiel de la mosqu\u00e9e de Lognes, entrez-y en paix. Bonne visite ! ;)\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/mosqueedelognes.com\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/mosqueedelognes.com\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/mosqueedelognes.com\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/mosqueedelognes.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Accueil\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mosqueedelognes.com\\\/#website\",\"url\":\"https:\\\/\\\/mosqueedelognes.com\\\/\",\"name\":\"Mosqu\u00e9e de Lognes \u2013 AFML\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/mosqueedelognes.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mosqueedelognes.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/mosqueedelognes.com\\\/#organization\",\"name\":\"Mosqu\u00e9e de Lognes \u2013 AFML\",\"url\":\"https:\\\/\\\/mosqueedelognes.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/mosqueedelognes.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/mosqueedelognes.com\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/Logo-wo-baseline-trans.png\",\"contentUrl\":\"http:\\\/\\\/mosqueedelognes.com\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/Logo-wo-baseline-trans.png\",\"width\":322,\"height\":208,\"caption\":\"Mosqu\u00e9e de Lognes \u2013 AFML\"},\"image\":{\"@id\":\"https:\\\/\\\/mosqueedelognes.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/mosqueedelognes\\\/\",\"https:\\\/\\\/x.com\\\/Mosquee_Lognes\",\"https:\\\/\\\/www.instagram.com\\\/mosqueedelognes\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@mosqueedelognesafml8658\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mosqu\u00e9e de Lognes \u2013 AFML","description":"\u0627\u0644\u0633\u0644\u0627\u0645 \u0639\u0644\u064a\u0643\u0645 \u0648 \u0631\u062d\u0645\u0629 \u0627\u0644\u0644\u0647 \u0648 \u0628\u0631\u0643\u0627\u062a\u0647 \u2013 Bienvenue sur le site officiel de la mosqu\u00e9e de Lognes, entrez-y en paix. Bonne visite ! ;)","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mosqueedelognes.com\/","og_locale":"en_US","og_type":"article","og_title":"Mosqu\u00e9e de Lognes \u2013 AFML","og_description":"\u0627\u0644\u0633\u0644\u0627\u0645 \u0639\u0644\u064a\u0643\u0645 \u0648 \u0631\u062d\u0645\u0629 \u0627\u0644\u0644\u0647 \u0648 \u0628\u0631\u0643\u0627\u062a\u0647 \u2013 Bienvenue sur le site officiel de la mosqu\u00e9e de Lognes, entrez-y en paix. Bonne visite ! ;)","og_url":"https:\/\/mosqueedelognes.com\/","og_site_name":"Mosqu\u00e9e de Lognes \u2013 AFML","article_publisher":"https:\/\/www.facebook.com\/mosqueedelognes\/","article_modified_time":"2022-12-15T10:07:14+00:00","twitter_card":"summary_large_image","twitter_site":"@Mosquee_Lognes","twitter_misc":{"Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/mosqueedelognes.com\/","url":"https:\/\/mosqueedelognes.com\/","name":"Mosqu\u00e9e de Lognes \u2013 AFML","isPartOf":{"@id":"https:\/\/mosqueedelognes.com\/#website"},"datePublished":"2021-05-19T13:32:36+00:00","dateModified":"2022-12-15T10:07:14+00:00","description":"\u0627\u0644\u0633\u0644\u0627\u0645 \u0639\u0644\u064a\u0643\u0645 \u0648 \u0631\u062d\u0645\u0629 \u0627\u0644\u0644\u0647 \u0648 \u0628\u0631\u0643\u0627\u062a\u0647 \u2013 Bienvenue sur le site officiel de la mosqu\u00e9e de Lognes, entrez-y en paix. Bonne visite ! ;)","breadcrumb":{"@id":"https:\/\/mosqueedelognes.com\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mosqueedelognes.com\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/mosqueedelognes.com\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/mosqueedelognes.com\/"},{"@type":"ListItem","position":2,"name":"Accueil"}]},{"@type":"WebSite","@id":"https:\/\/mosqueedelognes.com\/#website","url":"https:\/\/mosqueedelognes.com\/","name":"Mosqu\u00e9e de Lognes \u2013 AFML","description":"","publisher":{"@id":"https:\/\/mosqueedelognes.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mosqueedelognes.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/mosqueedelognes.com\/#organization","name":"Mosqu\u00e9e de Lognes \u2013 AFML","url":"https:\/\/mosqueedelognes.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/mosqueedelognes.com\/#\/schema\/logo\/image\/","url":"http:\/\/mosqueedelognes.com\/wp-content\/uploads\/2022\/11\/Logo-wo-baseline-trans.png","contentUrl":"http:\/\/mosqueedelognes.com\/wp-content\/uploads\/2022\/11\/Logo-wo-baseline-trans.png","width":322,"height":208,"caption":"Mosqu\u00e9e de Lognes \u2013 AFML"},"image":{"@id":"https:\/\/mosqueedelognes.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/mosqueedelognes\/","https:\/\/x.com\/Mosquee_Lognes","https:\/\/www.instagram.com\/mosqueedelognes\/","https:\/\/www.youtube.com\/@mosqueedelognesafml8658"]}]}},"_links":{"self":[{"href":"https:\/\/mosqueedelognes.com\/index.php\/wp-json\/wp\/v2\/pages\/862","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mosqueedelognes.com\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/mosqueedelognes.com\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/mosqueedelognes.com\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/mosqueedelognes.com\/index.php\/wp-json\/wp\/v2\/comments?post=862"}],"version-history":[{"count":48,"href":"https:\/\/mosqueedelognes.com\/index.php\/wp-json\/wp\/v2\/pages\/862\/revisions"}],"predecessor-version":[{"id":1129,"href":"https:\/\/mosqueedelognes.com\/index.php\/wp-json\/wp\/v2\/pages\/862\/revisions\/1129"}],"wp:attachment":[{"href":"https:\/\/mosqueedelognes.com\/index.php\/wp-json\/wp\/v2\/media?parent=862"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}